{"id":21658,"date":"2026-05-19T14:30:55","date_gmt":"2026-05-19T12:30:55","guid":{"rendered":"https:\/\/www.crl10.net\/?p=21658"},"modified":"2026-06-24T18:00:08","modified_gmt":"2026-06-24T16:00:08","slug":"stage-radio-photo","status":"publish","type":"post","link":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/","title":{"rendered":"Stage Radio-Photo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"21658\" class=\"elementor elementor-21658\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee7dcba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee7dcba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50b0d4ee\" data-id=\"50b0d4ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f248dae elementor-widget elementor-widget-text-editor\" data-id=\"4f248dae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a9Sarah Pedersen Kazes<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28eef899 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28eef899\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42dc8c94\" data-id=\"42dc8c94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1587b934 elementor-widget elementor-widget-heading\" data-id=\"1587b934\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-medium\">Comme beaucoup de stages de vacances propos\u00e9s par le CRL10, le stage radio-photo est un espace o\u00f9 l\u2019on apprend, d\u00e9couvre, cr\u00e9e, rencontre et s\u2019amuse pendant une semaine dans les centres Paris Anim\u2019 du 10e arrondissement. Encadr\u00e9 par Charlotte, journaliste et productrice radio, et \u00c9milie, photographe professionnelle, 11 jeunes \u00e2g\u00e9.e.s de 11 \u00e0 14 ans ont pu d\u00e9couvrir, pratiquer et exp\u00e9rimenter les m\u00e9tiers de la radio et de la photographie pendant les vacances d\u2019avril 2026.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ad9dca2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ad9dca2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68a3fe90\" data-id=\"68a3fe90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb2da2b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cb2da2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-595dc4ac elementor-widget elementor-widget-heading\" data-id=\"595dc4ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Rencontre avec les jeunes participant.e.s du stage Radio-Photo <span style=\"letter-spacing: 0px\">des centres Grange aux Belles et Jean Verdier<\/span><span style=\"letter-spacing: 0px\"><\/span><br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-695f1335 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"695f1335\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c0d69d4\" data-id=\"1c0d69d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bd5a0e7 elementor-widget elementor-widget-text-editor\" data-id=\"5bd5a0e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><b>Pendant une semaine, devenir reporter du 10e arrondissement<\/b><\/h4><p><span style=\"font-weight: 400;\">Comme beaucoup de stages de vacances propos\u00e9s par le CRL10, le stage radio-photo est un espace o\u00f9 l\u2019on apprend, d\u00e9couvre, cr\u00e9e, rencontre et s\u2019amuse pendant une semaine dans les centres Paris Anim\u2019 du 10e arrondissement.<\/span><\/p><p><span style=\"font-weight: 400;\">Encadr\u00e9 par Charlotte, journaliste et productrice radio, et \u00c9milie, photographe professionnelle, 11 jeunes de 11 \u00e0 14 ans ont pu d\u00e9couvrir, pratiquer et exp\u00e9rimenter les m\u00e9tiers de la radio et de la photographie pendant les vacances d\u2019avril 2026.<\/span><\/p><p><span style=\"font-weight: 400;\">R\u00e9parti entre ateliers radio le matin et photographie l\u2019apr\u00e8s-midi, le stage fonctionne comme une v\u00e9ritable immersion dans les pratiques du reportage photo-journalistique. Cette ann\u00e9e, le th\u00e8me choisi \u00e9tait celui du sport dans l\u2019espace public du 10e arrondissement.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00c0 travers micro-trottoirs, d\u00e9bats, chroniques, photographie de terrain et exp\u00e9rimentations visuelles, les participant\u00b7e\u00b7s ont explor\u00e9 la place du sport dans le quartier, mais aussi des sujets plus larges comme l\u2019acc\u00e8s aux \u00e9quipements sportifs publics ou encore la s\u00e9curit\u00e9 et la place des femmes dans le sport.<\/span><\/p><h4><b>Devenir reporter radio<\/b><\/h4><p><span style=\"font-weight: 400;\">Chaque matin, les jeunes se retrouvent autour des micros avec Charlotte pour construire leur propre \u00e9mission de radio. Tout au long de la semaine les jeunes reporters pr\u00e9parent la pr\u00e9sentation de l\u2019\u00e9mission, le billet d\u2019humeur, les chroniques musicales, le jingle, les micro-trottoirs, un d\u00e9bat et des fausses publicit\u00e9s. \u00c0 travers ces diff\u00e9rents exercices et l\u2019apprentissage des techniques de prise de son et de montage, les participant\u00b7e\u00b7s d\u00e9couvrent presque toutes les facettes du m\u00e9tier de journaliste radio.<\/span><\/p><p><span style=\"font-weight: 400;\">D\u00e8s le premier jour, Charlotte leur pr\u00e9sente les diff\u00e9rentes \u00e9tapes de fabrication d\u2019un podcast : \u00e9crire le fil conducteur de l\u2019\u00e9mission, pr\u00e9parer une interview, apprendre \u00e0 parler au micro, enregistrer sa voix, monter une \u00e9mission sur Audacity, nettoyer le son ou encore construire une programmation musicale.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32fe5e58 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32fe5e58\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6063ab5b\" data-id=\"6063ab5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bdca1a elementor-widget elementor-widget-image\" data-id=\"7bdca1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8603-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-21665\" alt=\"\" srcset=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8603-1-1024x683.jpg 1024w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8603-1-300x200.jpg 300w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8603-1-768x512.jpg 768w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8603-1-1536x1024.jpg 1536w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8603-1-2048x1365.jpg 2048w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8603-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-574c7263 elementor-widget elementor-widget-text-editor\" data-id=\"574c7263\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les jeunes partent ensuite dans le quartier r\u00e9aliser des micro-trottoirs autour des installations sportives du 10e arrondissement. Ils et elles interviewent des passant\u00b7e\u00b7s, des habitant\u00b7e\u00b7s ou des personnes en train d\u2019utiliser les \u00e9quipements sportifs pour nourrir leur \u00e9mission.<\/span><\/p><p><span style=\"font-weight: 400;\">La semaine se poursuit ensuite en studio avec le montage audio, l\u2019enregistrement des chroniques, le mixage et la finalisation de l\u2019\u00e9mission. L\u2019\u00e9mission r\u00e9alis\u00e9e pendant le stage sera ensuite disponible en ligne sous forme de podcast sur la cha\u00eene SoundCloud du CRL10 ou sur Spotify sur la cha\u00eene de podcast, Rouge Bric.<\/span><\/p><p><span style=\"font-weight: 400;\">Tout au long de la semaine, les participant\u00b7e\u00b7s apprennent, s&rsquo;entra\u00eenent, s\u2019entraident et apprennent les un\u00b7e\u00b7s des autres. Charlotte insiste sur cette id\u00e9e de collectif, elle dit aux jeunes :<\/span><\/p><p style=\"text-align: center;\"><em><strong>\u00ab Vous rentrez dans une \u00e9quipe o\u00f9, pendant une semaine, vous devenez reporter et reportrice. \u00bb<\/strong><\/em><\/p><p><span style=\"font-weight: 400;\">Ancienne professionnelle de Radio France, elle explique avoir eu envie de transmettre ce qu\u2019elle avait appris dans le milieu de la radio \u00e0 des plus jeunes.<\/span><\/p><h4><b>D\u00e9couvrir la photographie autrement<\/b><\/h4><p><span style=\"font-weight: 400;\">Apr\u00e8s cette matin\u00e9e passionnante, c\u2019est \u00c9milie qui prend le relais, et l\u2019apr\u00e8s-midi est alors consacr\u00e9e \u00e0 la photographie et aux pratiques qui l\u2019entourent.<\/span><\/p><p><span style=\"font-weight: 400;\">Le stage commence par une prise en main des appareils photo et une initiation aux r\u00e9glages manuels. Les jeunes d\u00e9couvrent les bases du triangle d&rsquo;exposition : ouverture, vitesse et ISO. Ils et elles apprennent \u00e0 comprendre la lumi\u00e8re, \u00e0 r\u00e9gler une bonne exposition et r\u00e9fl\u00e9chir au rendu qu\u2019ils souhaitent obtenir.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38069130 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38069130\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cade426\" data-id=\"4cade426\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a34591c elementor-widget elementor-widget-image\" data-id=\"a34591c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8583-1-1024x683.webp\" class=\"attachment-large size-large wp-image-21677\" alt=\"\" srcset=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8583-1-1024x683.webp 1024w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8583-1-300x200.webp 300w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8583-1-768x512.webp 768w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8583-1-1536x1024.jpg 1536w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8583-1-2048x1365.jpg 2048w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8583-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dcc020a elementor-widget elementor-widget-text-editor\" data-id=\"5dcc020a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Mais tr\u00e8s vite, le stage d\u00e9passe l\u2019apprentissage purement technique, car le mardi, les participant\u00b7e\u00b7s d\u00e9couvrent le laboratoire photo et exp\u00e9rimentent la photosensibilit\u00e9 \u00e0 travers la cr\u00e9ation de photogrammes. C&rsquo;est un processus pour r\u00e9aliser des photographies, avec la lumi\u00e8re et \u00e0 partir d\u2019objets pos\u00e9s sur du papier photosensible.<\/span><\/p><p><span style=\"font-weight: 400;\">Ensemble, ils et elles r\u00e9alisent \u00e9galement une grande composition collective \u00e0 partir de plantes pos\u00e9es sur ces papiers photosensibles et d\u2019une lumi\u00e8re allum\u00e9e pendant quelques secondes. Ce qui touche le papier, l\u00e0 o\u00f9 la lumi\u00e8re ne passe pas, reste blanc. Ce qui re\u00e7oit la lumi\u00e8re devient noir.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2c3b70 elementor-widget elementor-widget-image\" data-id=\"b2c3b70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"769\" height=\"1024\" src=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/1000045930-769x1024.webp\" class=\"attachment-large size-large wp-image-21676\" alt=\"\" srcset=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/1000045930-769x1024.webp 769w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/1000045930-225x300.webp 225w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/1000045930-768x1023.jpg 768w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/1000045930-1153x1536.jpg 1153w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/1000045930-1538x2048.jpg 1538w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/1000045930-scaled.webp 1442w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db8fafd elementor-widget elementor-widget-text-editor\" data-id=\"db8fafd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le reste de la semaine est consacr\u00e9 au travail de terrain autour du th\u00e8me du sport. Les jeunes photographient notamment sur le TEP Agn\u00e8s Tirop, nomm\u00e9 en hommage \u00e0 l\u2019athl\u00e8te k\u00e9nyane victime de f\u00e9minicide.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00c0 travers ces prises de vue, \u00c9milie les am\u00e8ne \u00e0 r\u00e9fl\u00e9chir \u00e0 la composition de l\u2019image, au cadrage, aux lignes de force, mais aussi \u00e0 la mani\u00e8re de repr\u00e9senter le mouvement, le flou, le corps ou l\u2019\u00e9nergie du sport. Elle insiste aussi sur une id\u00e9e importante :\u00a0<\/span><\/p><p style=\"text-align: center;\"><em><b>\u00ab Faire une photo, c\u2019est transmettre une sensibilit\u00e9. \u00bb\u00a0<\/b><\/em><\/p><p><span style=\"font-weight: 400;\">Chaque jour, les images r\u00e9alis\u00e9es sont observ\u00e9es collectivement, comment\u00e9es puis retravaill\u00e9es. Ces temps d\u2019\u00e9change permettent aux jeunes de progresser avant de retourner sur le terrain pour exp\u00e9rimenter de nouvelles prises de vue. \u00c0 l\u2019issue de la semaine, les jeunes s\u00e9lectionnent les photographies qui feront l&rsquo;objet d&rsquo;une exposition de fin de stage.\u00a0 Cette derni\u00e8re est mont\u00e9e par \u00c9milie, dans les semaines qui suivent, avec les photogrammes et photographies r\u00e9alis\u00e9es durant le stage.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-528e21d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"528e21d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5d2857\" data-id=\"b5d2857\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-447f170 elementor-widget elementor-widget-image\" data-id=\"447f170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8574-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-21675\" alt=\"\" srcset=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8574-1-1024x683.jpg 1024w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8574-1-300x200.webp 300w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8574-1-768x512.jpg 768w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8574-1-1536x1024.jpg 1536w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8574-1-2048x1365.jpg 2048w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8574-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0e8b79 elementor-widget elementor-widget-text-editor\" data-id=\"f0e8b79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><b>Une semaine pour cr\u00e9er, rencontrer et s\u2019exprimer<\/b><\/h4><p><span style=\"font-weight: 400;\">Au-del\u00e0 des apprentissages techniques, ce que les animatrices cherchent surtout \u00e0 transmettre pendant ce stage, c\u2019est un espace d\u2019expression. Tout au long de la semaine, une attention particuli\u00e8re est port\u00e9e \u00e0 l\u2019\u00e9coute des participant\u00b7e\u00b7s et \u00e0 la place laiss\u00e9e aux diff\u00e9rentes personnalit\u00e9s du groupe. Chacun\u00b7e peut proposer des id\u00e9es, essayer, se tromper, recommencer et trouver sa mani\u00e8re de participer. L\u2019ambiance entre les jeunes, les \u00e9changes et l\u2019\u00e9nergie collective font pleinement partie du stage.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00c0 la fin de la semaine, les familles peuvent d\u00e9couvrir le travail r\u00e9alis\u00e9 : \u00e9couter le podcast produit par les jeunes et visiter l\u2019exposition photographique qui rassemble \u00e0 la fois des images individuelles et les cr\u00e9ations collectives r\u00e9alis\u00e9es en laboratoire photo.<\/span><\/p><p><span style=\"font-weight: 400;\">Le stage radio-photo fait partie des nombreux stages propos\u00e9s par le CRL10 pendant les vacances scolaires, autour de pratiques artistiques, culturelles et m\u00e9diatiques destin\u00e9es aux jeunes du 10e arrondissement.<\/span><\/p><p><span style=\"font-weight: 400;\">Pour \u00e9couter le podcast, vous pouvez chercher sur Spotify : <\/span><i><span style=\"font-weight: 400;\">\u00ab Radio Passerelle : le sport pour tous et toutes en ville \u00bb. Ateliers radio de Rouge Bric <\/span><\/i><span style=\"font-weight: 400;\">ou alors cliquer sur le lien ci-dessous:<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce52fdc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce52fdc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab01604\" data-id=\"ab01604\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5aabc99 elementor-widget elementor-widget-shortcode\" data-id=\"5aabc99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><iframe data-testid=\"embed-iframe\" style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed\/episode\/32JJkd9qgdZ4Z17s1j5ld3?utm_source=generator\" width=\"100%\" height=\"152\" frameBorder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\"><\/iframe><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16ccd837 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16ccd837\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c2c3327\" data-id=\"5c2c3327\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-329dfe2 elementor-widget elementor-widget-image\" data-id=\"329dfe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8522-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-21674\" alt=\"\" srcset=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8522-1-1024x683.jpg 1024w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8522-1-300x200.webp 300w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8522-1-768x512.jpg 768w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8522-1-1536x1024.jpg 1536w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8522-1-2048x1365.jpg 2048w, https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8522-1-scaled.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30a0c476 elementor-widget elementor-widget-text-editor\" data-id=\"30a0c476\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Entretiens r\u00e9alis\u00e9 par Sarah Pedersen Kazes, r\u00e9dactrice du journal associatif du CRL 10.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Comme beaucoup de stages de vacances propos\u00e9s par le CRL10, le stage radio-photo est un espace o\u00f9 l\u2019on apprend, d\u00e9couvre, cr\u00e9e, rencontre et s\u2019amuse pendant une semaine dans les centres Paris Anim\u2019 du 10e arrondissement. Encadr\u00e9 par Charlotte, journaliste et productrice radio, et \u00c9milie, photographe professionnelle, 11 jeunes de 11 \u00e0 14 ans ont pu d\u00e9couvrir, pratiquer et exp\u00e9rimenter les m\u00e9tiers de la radio et de la photographie pendant les vacances d\u2019avril 2026.\u200b<\/p>\n","protected":false},"author":15,"featured_media":21660,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[82,159,161],"tags":[],"class_list":["post-21658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-journal","category-n3","category-vie-associative-n3"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stage Radio-Photo - CRL10<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stage Radio-Photo - CRL10\" \/>\n<meta property=\"og:description\" content=\"Comme beaucoup de stages de vacances propos\u00e9s par le CRL10, le stage radio-photo est un espace o\u00f9 l\u2019on apprend, d\u00e9couvre, cr\u00e9e, rencontre et s\u2019amuse pendant une semaine dans les centres Paris Anim\u2019 du 10e arrondissement. Encadr\u00e9 par Charlotte, journaliste et productrice radio, et \u00c9milie, photographe professionnelle, 11 jeunes de 11 \u00e0 14 ans ont pu d\u00e9couvrir, pratiquer et exp\u00e9rimenter les m\u00e9tiers de la radio et de la photographie pendant les vacances d\u2019avril 2026.\u200b\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/\" \/>\n<meta property=\"og:site_name\" content=\"CRL10\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/assocrl10\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-19T12:30:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T16:00:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8536-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sarah Pedersen Kazes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Pedersen Kazes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/\"},\"author\":{\"name\":\"Sarah Pedersen Kazes\",\"@id\":\"https:\\\/\\\/www.crl10.net\\\/#\\\/schema\\\/person\\\/58942ee1c374729a115a255920971037\"},\"headline\":\"Stage Radio-Photo\",\"datePublished\":\"2026-05-19T12:30:55+00:00\",\"dateModified\":\"2026-06-24T16:00:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/\"},\"wordCount\":1200,\"publisher\":{\"@id\":\"https:\\\/\\\/www.crl10.net\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.crl10.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DSCF8536-1-scaled.jpg\",\"articleSection\":[\"Journal\",\"n\u00b03\",\"Vie associative\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/\",\"url\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/\",\"name\":\"Stage Radio-Photo - CRL10\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.crl10.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.crl10.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DSCF8536-1-scaled.jpg\",\"datePublished\":\"2026-05-19T12:30:55+00:00\",\"dateModified\":\"2026-06-24T16:00:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.crl10.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DSCF8536-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.crl10.net\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DSCF8536-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/2026\\\/05\\\/19\\\/stage-radio-photo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.crl10.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stage Radio-Photo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.crl10.net\\\/#website\",\"url\":\"https:\\\/\\\/www.crl10.net\\\/\",\"name\":\"CRL10\",\"description\":\"Education populaire, Paris 10e\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.crl10.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.crl10.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.crl10.net\\\/#organization\",\"name\":\"CRL10\",\"url\":\"https:\\\/\\\/www.crl10.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.crl10.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.crl10.net\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CRL_logo_site.jpg\",\"contentUrl\":\"https:\\\/\\\/www.crl10.net\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/CRL_logo_site.jpg\",\"width\":350,\"height\":100,\"caption\":\"CRL10\"},\"image\":{\"@id\":\"https:\\\/\\\/www.crl10.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/assocrl10\",\"https:\\\/\\\/www.instagram.com\\\/asso_crl10\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@asso_crl10\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/crl10\\\/\",\"https:\\\/\\\/soundcloud.com\\\/user-291561763\",\"https:\\\/\\\/www.tiktok.com\\\/@asso_crl10\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.crl10.net\\\/#\\\/schema\\\/person\\\/58942ee1c374729a115a255920971037\",\"name\":\"Sarah Pedersen Kazes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac6d72dc05681bf07a59dec84a078ef0372d8e5232925c5f3c7b1791d3968d5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac6d72dc05681bf07a59dec84a078ef0372d8e5232925c5f3c7b1791d3968d5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac6d72dc05681bf07a59dec84a078ef0372d8e5232925c5f3c7b1791d3968d5d?s=96&d=mm&r=g\",\"caption\":\"Sarah Pedersen Kazes\"},\"url\":\"https:\\\/\\\/www.crl10.net\\\/index.php\\\/author\\\/sarah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stage Radio-Photo - CRL10","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/","og_locale":"fr_FR","og_type":"article","og_title":"Stage Radio-Photo - CRL10","og_description":"Comme beaucoup de stages de vacances propos\u00e9s par le CRL10, le stage radio-photo est un espace o\u00f9 l\u2019on apprend, d\u00e9couvre, cr\u00e9e, rencontre et s\u2019amuse pendant une semaine dans les centres Paris Anim\u2019 du 10e arrondissement. Encadr\u00e9 par Charlotte, journaliste et productrice radio, et \u00c9milie, photographe professionnelle, 11 jeunes de 11 \u00e0 14 ans ont pu d\u00e9couvrir, pratiquer et exp\u00e9rimenter les m\u00e9tiers de la radio et de la photographie pendant les vacances d\u2019avril 2026.\u200b","og_url":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/","og_site_name":"CRL10","article_publisher":"https:\/\/www.facebook.com\/assocrl10","article_published_time":"2026-05-19T12:30:55+00:00","article_modified_time":"2026-06-24T16:00:08+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8536-1-scaled.jpg","type":"image\/jpeg"}],"author":"Sarah Pedersen Kazes","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sarah Pedersen Kazes","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/#article","isPartOf":{"@id":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/"},"author":{"name":"Sarah Pedersen Kazes","@id":"https:\/\/www.crl10.net\/#\/schema\/person\/58942ee1c374729a115a255920971037"},"headline":"Stage Radio-Photo","datePublished":"2026-05-19T12:30:55+00:00","dateModified":"2026-06-24T16:00:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/"},"wordCount":1200,"publisher":{"@id":"https:\/\/www.crl10.net\/#organization"},"image":{"@id":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8536-1-scaled.jpg","articleSection":["Journal","n\u00b03","Vie associative"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/","url":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/","name":"Stage Radio-Photo - CRL10","isPartOf":{"@id":"https:\/\/www.crl10.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/#primaryimage"},"image":{"@id":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8536-1-scaled.jpg","datePublished":"2026-05-19T12:30:55+00:00","dateModified":"2026-06-24T16:00:08+00:00","breadcrumb":{"@id":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/#primaryimage","url":"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8536-1-scaled.jpg","contentUrl":"https:\/\/www.crl10.net\/wp-content\/uploads\/2026\/05\/DSCF8536-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.crl10.net\/index.php\/2026\/05\/19\/stage-radio-photo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.crl10.net\/"},{"@type":"ListItem","position":2,"name":"Stage Radio-Photo"}]},{"@type":"WebSite","@id":"https:\/\/www.crl10.net\/#website","url":"https:\/\/www.crl10.net\/","name":"CRL10","description":"Education populaire, Paris 10e","publisher":{"@id":"https:\/\/www.crl10.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.crl10.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.crl10.net\/#organization","name":"CRL10","url":"https:\/\/www.crl10.net\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.crl10.net\/#\/schema\/logo\/image\/","url":"https:\/\/www.crl10.net\/wp-content\/uploads\/2022\/07\/CRL_logo_site.jpg","contentUrl":"https:\/\/www.crl10.net\/wp-content\/uploads\/2022\/07\/CRL_logo_site.jpg","width":350,"height":100,"caption":"CRL10"},"image":{"@id":"https:\/\/www.crl10.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/assocrl10","https:\/\/www.instagram.com\/asso_crl10\/","https:\/\/www.youtube.com\/@asso_crl10","https:\/\/www.linkedin.com\/company\/crl10\/","https:\/\/soundcloud.com\/user-291561763","https:\/\/www.tiktok.com\/@asso_crl10"]},{"@type":"Person","@id":"https:\/\/www.crl10.net\/#\/schema\/person\/58942ee1c374729a115a255920971037","name":"Sarah Pedersen Kazes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ac6d72dc05681bf07a59dec84a078ef0372d8e5232925c5f3c7b1791d3968d5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac6d72dc05681bf07a59dec84a078ef0372d8e5232925c5f3c7b1791d3968d5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac6d72dc05681bf07a59dec84a078ef0372d8e5232925c5f3c7b1791d3968d5d?s=96&d=mm&r=g","caption":"Sarah Pedersen Kazes"},"url":"https:\/\/www.crl10.net\/index.php\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/posts\/21658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/comments?post=21658"}],"version-history":[{"count":46,"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/posts\/21658\/revisions"}],"predecessor-version":[{"id":22521,"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/posts\/21658\/revisions\/22521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/media\/21660"}],"wp:attachment":[{"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/media?parent=21658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/categories?post=21658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.crl10.net\/index.php\/wp-json\/wp\/v2\/tags?post=21658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}